{"id":6016,"date":"2022-06-07T07:16:59","date_gmt":"2022-06-07T06:16:59","guid":{"rendered":"https:\/\/gambling6.com\/?p=6016"},"modified":"2022-06-09T15:53:41","modified_gmt":"2022-06-09T14:53:41","slug":"melhores-torneios-de-poquer-sit-and-go-super-turbo","status":"publish","type":"post","link":"https:\/\/gambling6.com\/pt-pt\/melhores-torneios-de-poquer-sit-and-go-super-turbo\/","title":{"rendered":"Torneios de p\u00f3quer &#8220;Sit and Go&#8221; de super-turbo recomendados"},"content":{"rendered":"<h2>Os torneios de p\u00f3quer mais r\u00e1pidos da SNG<\/h2>\n<p>Nem sequer me lembro que sala de p\u00f3quer come\u00e7ou isto, mas a maioria das salas de p\u00f3quer tem agora este tipo de jogo em oferta. Estou a falar dos torneios Spin and Go das Pokerstars, ou Twister da Bet365. Todos estes torneios t\u00eam uma coisa em comum: pr\u00e9mio monet\u00e1rio definido aleatoriamente, uma pilha curta, estrutura de persianas extremamente r\u00e1pida, e um pagamento de pr\u00e9mio de vencedor-tudo. Esses jogos tornaram-se extremamente populares e s\u00e3o \u00f3ptimos criadores de dinheiro para sites de p\u00f3quer.<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"alignright size-medium wp-image-3003\" src=\"https:\/\/gambling6.com\/wp-content\/uploads\/2022\/04\/pokerpocketkings-300x200.jpg\" alt=\"SNG torneio de p\u00f3quer\" width=\"300\" height=\"200\" srcset=\"https:\/\/gambling6.com\/wp-content\/uploads\/2022\/04\/pokerpocketkings-300x200.jpg 300w, https:\/\/gambling6.com\/wp-content\/uploads\/2022\/04\/pokerpocketkings.jpg 424w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/>Mas nem todos esses jogos podem ser recomendados com uma boa consci\u00eancia &#8211; pelo menos n\u00e3o a um jogador que realmente queira ganhar dinheiro a jogar p\u00f3quer. A parte mais importante \u00e9 como o dinheiro do pr\u00e9mio real \u00e9 determinado. Vamos assumir que se escolhe um torneio de $10, e que se come\u00e7a com 3 m\u00e3os. Normalmente, haveria um total de $30 a ser distribu\u00eddo (neste caso, apenas o vencedor \u00e9 pago), mas o pagamento real \u00e9 definido por um gerador de n\u00fameros aleat\u00f3rios (RNG). Assim, o ganho m\u00ednimo seria de 20$ em vez de 30$ &#8211; os restantes 10$ seriam utilizados pela sala de poker para cobrir todos os jogos em que o ganho real \u00e9 fixado em 60$, 120$, ou mesmo 100.000$. Todas as salas publicam a probabilidade de cada montante de pr\u00e9mio em dinheiro aparecer antes do in\u00edcio do jogo.<\/p>\n<h2>Girar e Ir fazer batota<\/h2>\n<p>\u00c9 aqui que se torna complicado, e onde voc\u00ea como jogador n\u00e3o tem forma de saber se o jogo \u00e9 justo. Tomo aqui como exemplo as Pokerstars. E se a sala de poker lhe disser que \u00e9 poss\u00edvel que, devido ao RNG, tenha a oportunidade de jogar por $10.000 com um buy-in de $10, mas na verdade isso nunca acontece?<\/p>\n<p>Pessoalmente, j\u00e1 joguei v\u00e1rias centenas desses Spin e Gos em Pokerstars, e nunca vi o RNG parar com um pr\u00e9mio monet\u00e1rio superior a 4 vezes o buy-in. Talvez a minha amostra n\u00e3o seja suficientemente grande, mas duvido que esses enormes pagamentos alguma vez aconte\u00e7am. E se isso for verdade, ent\u00e3o Pokerstars est\u00e1 a retirar uma percentagem dos buy-ins que \u00e9 demasiado alta &#8211; suficientemente alta para que nenhum jogador seja capaz de alguma vez vencer esses jogos a longo prazo. Portanto, Pokerstars (que, por uma s\u00e9rie de raz\u00f5es que n\u00e3o considero de qualquer modo dignas de confian\u00e7a) n\u00e3o \u00e9 uma boa op\u00e7\u00e3o.<\/p>\n<h2>Demasiado apostado<\/h2>\n<p>O ritmo super-turbo desses torneios significa que h\u00e1 mais sorte em compara\u00e7\u00e3o com um torneio regular. Mas isso n\u00e3o faz mal, na verdade, \u00e9 uma das coisas que torna este tipo de jogo atraente para muitos. Mas e se acrescentarmos outra regra, que diz que s\u00f3 se joga p\u00f3quer normal durante os primeiros dois minutos, e depois disso, todos os jogadores s\u00e3o all-in para cada m\u00e3o at\u00e9 restar um vencedor com todas as fichas? Como \u00e9 que isso ainda \u00e9 p\u00f3quer? Certo. Mas mesmo assim, alguns jogadores podem gostar deles.<\/p>\n<p>888 tem uma das melhores escolhas de torneios com buy-in baixo e m\u00e9dio, e t\u00eam sido considerados de confian\u00e7a h\u00e1 muitos anos, por isso recomendo-os vivamente<a class=\"thirstylink\" title=\"888 poker en\" href=\"https:\/\/gambling6.com\/go\/888-poker-en\/\" target=\"_blank\" rel=\"nofollow noopener\"> (clique aqui para visitar o 888)<\/a>.<\/p>\n<h2>Portanto, qual a sala com a melhor super-turbo Sit and Go&#8217;s<\/h2>\n<p>Na minha opini\u00e3o, os melhores jogos est\u00e3o a ser oferecidos pelo 888 Poker. Aqui, eles v\u00e3o pelo nome de &#8220;Blast&#8221;, e os buy-ins come\u00e7am com 0,50 euros e v\u00e3o at\u00e9 aos 100 euros. Com um buy-in de 100 euros, o pagamento mais alto poss\u00edvel \u00e9 de 100.000 euros (em oposi\u00e7\u00e3o a 1 milh\u00e3o de d\u00f3lares em Pokerstars, mas duvido que algu\u00e9m j\u00e1 tenha ganho tanto com um Spin and Go at Stars). Tamb\u00e9m j\u00e1 joguei algumas centenas delas, e na verdade tive um torneio de 10 euros em que acabei por jogar pelo m\u00e1ximo de 10.000 euros. Infelizmente, n\u00e3o ganhei este, mas pelo menos sei que o RNG n\u00e3o faz batota aqui.<\/p>\n<p>Portanto, se gostar desses jogos, 888 \u00e9 a sala certa para isso. <a class=\"thirstylink\" title=\"888 poker en\" href=\"https:\/\/gambling6.com\/go\/888-poker-en\/\" target=\"_blank\" rel=\"nofollow noopener\">Siga este link e experimente os seus torneios Blast hoje mesmo!<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Os torneios de p\u00f3quer mais r\u00e1pidos da SNG Nem sequer me lembro que sala de p\u00f3quer come\u00e7ou isto, mas a maioria das salas de p\u00f3quer tem agora este tipo de jogo em oferta. Estou a falar dos torneios Spin and Go das Pokerstars, ou Twister da Bet365. Todos estes torneios t\u00eam uma coisa em comum: [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[646,87,666],"tags":[],"class_list":["post-6016","post","type-post","status-publish","format-standard","hentry","category-melhores-sites-de-apostas-por-criterios","category-noticias-desportivas","category-salas-de-poquer-por-criterios"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Melhor Senta Super-Turbo e Go torneios de p\u00f3quer<\/title>\n<meta name=\"description\" content=\"Spin e Go, Explos\u00e3o, Rush ou Twister? Informa\u00e7\u00e3o sobre os melhores torneios Super Turbo Sit and Go\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/gambling6.com\/pt-pt\/melhores-torneios-de-poquer-sit-and-go-super-turbo\/\" \/>\n<meta property=\"og:locale\" content=\"pt_PT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Melhor Senta Super-Turbo e Go torneios de p\u00f3quer\" \/>\n<meta property=\"og:description\" content=\"Spin e Go, Explos\u00e3o, Rush ou Twister? Informa\u00e7\u00e3o sobre os melhores torneios Super Turbo Sit and Go\" \/>\n<meta property=\"og:url\" content=\"https:\/\/gambling6.com\/pt-pt\/melhores-torneios-de-poquer-sit-and-go-super-turbo\/\" \/>\n<meta property=\"og:site_name\" content=\"Gambling6\" \/>\n<meta property=\"article:published_time\" content=\"2022-06-07T06:16:59+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2022-06-09T14:53:41+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/gambling6.com\/wp-content\/uploads\/2022\/04\/pokerpocketkings.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"424\" \/>\n\t<meta property=\"og:image:height\" content=\"283\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Catfish\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Catfish\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo estimado de leitura\" \/>\n\t<meta name=\"twitter:data2\" content=\"4 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/gambling6.com\\\/pt-pt\\\/melhores-torneios-de-poquer-sit-and-go-super-turbo\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/gambling6.com\\\/pt-pt\\\/melhores-torneios-de-poquer-sit-and-go-super-turbo\\\/\"},\"author\":{\"name\":\"Catfish\",\"@id\":\"https:\\\/\\\/gambling6.com\\\/pt-pt\\\/#\\\/schema\\\/person\\\/d093de87a44a018ef67117d02d86ddaf\"},\"headline\":\"Torneios de p\u00f3quer &#8220;Sit and Go&#8221; de super-turbo recomendados\",\"datePublished\":\"2022-06-07T06:16:59+00:00\",\"dateModified\":\"2022-06-09T14:53:41+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/gambling6.com\\\/pt-pt\\\/melhores-torneios-de-poquer-sit-and-go-super-turbo\\\/\"},\"wordCount\":703,\"image\":{\"@id\":\"https:\\\/\\\/gambling6.com\\\/pt-pt\\\/melhores-torneios-de-poquer-sit-and-go-super-turbo\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/gambling6.com\\\/wp-content\\\/uploads\\\/2022\\\/04\\\/pokerpocketkings-300x200.jpg\",\"articleSection\":[\"Melhores sites de apostas por crit\u00e9rios\",\"Not\u00edcias Desportivas\",\"Salas de p\u00f3quer por crit\u00e9rios\"],\"inLanguage\":\"pt-PT\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/gambling6.com\\\/pt-pt\\\/melhores-torneios-de-poquer-sit-and-go-super-turbo\\\/\",\"url\":\"https:\\\/\\\/gambling6.com\\\/pt-pt\\\/melhores-torneios-de-poquer-sit-and-go-super-turbo\\\/\",\"name\":\"Melhor Senta Super-Turbo e Go torneios de p\u00f3quer\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/gambling6.com\\\/pt-pt\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/gambling6.com\\\/pt-pt\\\/melhores-torneios-de-poquer-sit-and-go-super-turbo\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/gambling6.com\\\/pt-pt\\\/melhores-torneios-de-poquer-sit-and-go-super-turbo\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/gambling6.com\\\/wp-content\\\/uploads\\\/2022\\\/04\\\/pokerpocketkings-300x200.jpg\",\"datePublished\":\"2022-06-07T06:16:59+00:00\",\"dateModified\":\"2022-06-09T14:53:41+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/gambling6.com\\\/pt-pt\\\/#\\\/schema\\\/person\\\/d093de87a44a018ef67117d02d86ddaf\"},\"description\":\"Spin e Go, Explos\u00e3o, Rush ou Twister? Informa\u00e7\u00e3o sobre os melhores torneios Super Turbo Sit and Go\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/gambling6.com\\\/pt-pt\\\/melhores-torneios-de-poquer-sit-and-go-super-turbo\\\/#breadcrumb\"},\"inLanguage\":\"pt-PT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/gambling6.com\\\/pt-pt\\\/melhores-torneios-de-poquer-sit-and-go-super-turbo\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-PT\",\"@id\":\"https:\\\/\\\/gambling6.com\\\/pt-pt\\\/melhores-torneios-de-poquer-sit-and-go-super-turbo\\\/#primaryimage\",\"url\":\"https:\\\/\\\/gambling6.com\\\/wp-content\\\/uploads\\\/2022\\\/04\\\/pokerpocketkings-300x200.jpg\",\"contentUrl\":\"https:\\\/\\\/gambling6.com\\\/wp-content\\\/uploads\\\/2022\\\/04\\\/pokerpocketkings-300x200.jpg\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/gambling6.com\\\/pt-pt\\\/melhores-torneios-de-poquer-sit-and-go-super-turbo\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/gambling6.com\\\/pt-pt\\\/home\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Torneios de p\u00f3quer &#8220;Sit and Go&#8221; de super-turbo recomendados\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/gambling6.com\\\/pt-pt\\\/#website\",\"url\":\"https:\\\/\\\/gambling6.com\\\/pt-pt\\\/\",\"name\":\"Gambling6\",\"description\":\"\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/gambling6.com\\\/pt-pt\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-PT\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/gambling6.com\\\/pt-pt\\\/#\\\/schema\\\/person\\\/d093de87a44a018ef67117d02d86ddaf\",\"name\":\"Catfish\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-PT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/32edfa28ccbf005c231538b245a2670a36c7f33f2d3a9ab09e50843b363f2821?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/32edfa28ccbf005c231538b245a2670a36c7f33f2d3a9ab09e50843b363f2821?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/32edfa28ccbf005c231538b245a2670a36c7f33f2d3a9ab09e50843b363f2821?s=96&d=mm&r=g\",\"caption\":\"Catfish\"},\"sameAs\":[\"http:\\\/\\\/gambling6.com\"],\"url\":\"https:\\\/\\\/gambling6.com\\\/pt-pt\\\/author\\\/catfish\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Melhor Senta Super-Turbo e Go torneios de p\u00f3quer","description":"Spin e Go, Explos\u00e3o, Rush ou Twister? Informa\u00e7\u00e3o sobre os melhores torneios Super Turbo Sit and Go","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/gambling6.com\/pt-pt\/melhores-torneios-de-poquer-sit-and-go-super-turbo\/","og_locale":"pt_PT","og_type":"article","og_title":"Melhor Senta Super-Turbo e Go torneios de p\u00f3quer","og_description":"Spin e Go, Explos\u00e3o, Rush ou Twister? Informa\u00e7\u00e3o sobre os melhores torneios Super Turbo Sit and Go","og_url":"https:\/\/gambling6.com\/pt-pt\/melhores-torneios-de-poquer-sit-and-go-super-turbo\/","og_site_name":"Gambling6","article_published_time":"2022-06-07T06:16:59+00:00","article_modified_time":"2022-06-09T14:53:41+00:00","og_image":[{"width":424,"height":283,"url":"https:\/\/gambling6.com\/wp-content\/uploads\/2022\/04\/pokerpocketkings.jpg","type":"image\/jpeg"}],"author":"Catfish","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"Catfish","Tempo estimado de leitura":"4 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/gambling6.com\/pt-pt\/melhores-torneios-de-poquer-sit-and-go-super-turbo\/#article","isPartOf":{"@id":"https:\/\/gambling6.com\/pt-pt\/melhores-torneios-de-poquer-sit-and-go-super-turbo\/"},"author":{"name":"Catfish","@id":"https:\/\/gambling6.com\/pt-pt\/#\/schema\/person\/d093de87a44a018ef67117d02d86ddaf"},"headline":"Torneios de p\u00f3quer &#8220;Sit and Go&#8221; de super-turbo recomendados","datePublished":"2022-06-07T06:16:59+00:00","dateModified":"2022-06-09T14:53:41+00:00","mainEntityOfPage":{"@id":"https:\/\/gambling6.com\/pt-pt\/melhores-torneios-de-poquer-sit-and-go-super-turbo\/"},"wordCount":703,"image":{"@id":"https:\/\/gambling6.com\/pt-pt\/melhores-torneios-de-poquer-sit-and-go-super-turbo\/#primaryimage"},"thumbnailUrl":"https:\/\/gambling6.com\/wp-content\/uploads\/2022\/04\/pokerpocketkings-300x200.jpg","articleSection":["Melhores sites de apostas por crit\u00e9rios","Not\u00edcias Desportivas","Salas de p\u00f3quer por crit\u00e9rios"],"inLanguage":"pt-PT"},{"@type":"WebPage","@id":"https:\/\/gambling6.com\/pt-pt\/melhores-torneios-de-poquer-sit-and-go-super-turbo\/","url":"https:\/\/gambling6.com\/pt-pt\/melhores-torneios-de-poquer-sit-and-go-super-turbo\/","name":"Melhor Senta Super-Turbo e Go torneios de p\u00f3quer","isPartOf":{"@id":"https:\/\/gambling6.com\/pt-pt\/#website"},"primaryImageOfPage":{"@id":"https:\/\/gambling6.com\/pt-pt\/melhores-torneios-de-poquer-sit-and-go-super-turbo\/#primaryimage"},"image":{"@id":"https:\/\/gambling6.com\/pt-pt\/melhores-torneios-de-poquer-sit-and-go-super-turbo\/#primaryimage"},"thumbnailUrl":"https:\/\/gambling6.com\/wp-content\/uploads\/2022\/04\/pokerpocketkings-300x200.jpg","datePublished":"2022-06-07T06:16:59+00:00","dateModified":"2022-06-09T14:53:41+00:00","author":{"@id":"https:\/\/gambling6.com\/pt-pt\/#\/schema\/person\/d093de87a44a018ef67117d02d86ddaf"},"description":"Spin e Go, Explos\u00e3o, Rush ou Twister? Informa\u00e7\u00e3o sobre os melhores torneios Super Turbo Sit and Go","breadcrumb":{"@id":"https:\/\/gambling6.com\/pt-pt\/melhores-torneios-de-poquer-sit-and-go-super-turbo\/#breadcrumb"},"inLanguage":"pt-PT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/gambling6.com\/pt-pt\/melhores-torneios-de-poquer-sit-and-go-super-turbo\/"]}]},{"@type":"ImageObject","inLanguage":"pt-PT","@id":"https:\/\/gambling6.com\/pt-pt\/melhores-torneios-de-poquer-sit-and-go-super-turbo\/#primaryimage","url":"https:\/\/gambling6.com\/wp-content\/uploads\/2022\/04\/pokerpocketkings-300x200.jpg","contentUrl":"https:\/\/gambling6.com\/wp-content\/uploads\/2022\/04\/pokerpocketkings-300x200.jpg"},{"@type":"BreadcrumbList","@id":"https:\/\/gambling6.com\/pt-pt\/melhores-torneios-de-poquer-sit-and-go-super-turbo\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/gambling6.com\/pt-pt\/home\/"},{"@type":"ListItem","position":2,"name":"Torneios de p\u00f3quer &#8220;Sit and Go&#8221; de super-turbo recomendados"}]},{"@type":"WebSite","@id":"https:\/\/gambling6.com\/pt-pt\/#website","url":"https:\/\/gambling6.com\/pt-pt\/","name":"Gambling6","description":"","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/gambling6.com\/pt-pt\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-PT"},{"@type":"Person","@id":"https:\/\/gambling6.com\/pt-pt\/#\/schema\/person\/d093de87a44a018ef67117d02d86ddaf","name":"Catfish","image":{"@type":"ImageObject","inLanguage":"pt-PT","@id":"https:\/\/secure.gravatar.com\/avatar\/32edfa28ccbf005c231538b245a2670a36c7f33f2d3a9ab09e50843b363f2821?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/32edfa28ccbf005c231538b245a2670a36c7f33f2d3a9ab09e50843b363f2821?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/32edfa28ccbf005c231538b245a2670a36c7f33f2d3a9ab09e50843b363f2821?s=96&d=mm&r=g","caption":"Catfish"},"sameAs":["http:\/\/gambling6.com"],"url":"https:\/\/gambling6.com\/pt-pt\/author\/catfish\/"}]}},"_links":{"self":[{"href":"https:\/\/gambling6.com\/pt-pt\/wp-json\/wp\/v2\/posts\/6016","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/gambling6.com\/pt-pt\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/gambling6.com\/pt-pt\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/gambling6.com\/pt-pt\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/gambling6.com\/pt-pt\/wp-json\/wp\/v2\/comments?post=6016"}],"version-history":[{"count":1,"href":"https:\/\/gambling6.com\/pt-pt\/wp-json\/wp\/v2\/posts\/6016\/revisions"}],"predecessor-version":[{"id":6017,"href":"https:\/\/gambling6.com\/pt-pt\/wp-json\/wp\/v2\/posts\/6016\/revisions\/6017"}],"wp:attachment":[{"href":"https:\/\/gambling6.com\/pt-pt\/wp-json\/wp\/v2\/media?parent=6016"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/gambling6.com\/pt-pt\/wp-json\/wp\/v2\/categories?post=6016"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/gambling6.com\/pt-pt\/wp-json\/wp\/v2\/tags?post=6016"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}